
{"id":2000,"date":"2021-07-08T11:42:20","date_gmt":"2021-07-08T09:42:20","guid":{"rendered":"https:\/\/www.smart-ai-work.de\/?p=2000"},"modified":"2021-07-09T13:53:03","modified_gmt":"2021-07-09T11:53:03","slug":"vortrag-bei-der-initiative-wirtschaft-und-arbeit-4-0-nordrhein-westfalen-smartaiwork-sachbearbeitung-der-zukunft","status":"publish","type":"post","link":"https:\/\/www.smart-ai-work.de\/index.php\/vortrag-bei-der-initiative-wirtschaft-und-arbeit-4-0-nordrhein-westfalen-smartaiwork-sachbearbeitung-der-zukunft\/","title":{"rendered":"Vortrag bei der Initiative \u201eWirtschaft und Arbeit 4.0\u201c Nordrhein-Westfalen \u201eSmartAIWork \u2013 Sachbearbeitung der Zukunft\u201c"},"content":{"rendered":"<p><strong>Initiative Wirtschaft &amp; Arbeit 4.0<\/strong><br \/>\nDie Landesregierung Nordrhein-Westfalen sucht gemeinsam mit Gewerkschaften, Arbeitgebern und Wissenschaft Wege, um die Digitalisierung so zu gestalten, dass der Fortschritt den Menschen dient und Arbeit flexibler, sicherer und interessanter wird.<\/p>\n<p><strong>Best Practices<\/strong><br \/>\nDie Unternehmen in Nordrhein-Westfalen sind mitten in der digitalen Transformation. Wenn auch Sie sich mit Ihrem Unternehmen auf den Weg machen wollen, finden Sie hier Anregungen, wie Unternehmen den digitalen Wandel gemeinsam mit ihren Besch\u00e4ftigten gestalten k\u00f6nnen, unter anderem aus dem Projekt SmartAIwork.<\/p>\n<p><a class=\"button6\" href=\"https:\/\/www.iwa.nrw.de\/smartaiwork-sachbearbeitung-mit-ki-produktivitaetsfoerdernd-und-menschengerecht-gestalten\" target=\"_blank\" rel=\"noopener\">Zum SmartAIwork Vortrag<i class=\"wp-svg-enter enter\"><\/i><\/a><\/p>\n<p>Quelle: <strong>Initiative Wirtschaft &amp; Arbeit 4.0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Initiative Wirtschaft &amp; Arbeit 4.0 Die Landesregierung Nordrhein-Westfalen sucht gemeinsam mit Gewerkschaften, Arbeitgebern und Wissenschaft Wege, um die Digitalisierung so zu gestalten, dass der Fortschritt den Menschen dient und Arbeit flexibler, sicherer und interessanter wird. Best Practices Die Unternehmen in Nordrhein-Westfalen sind mitten in der digitalen Transformation. Wenn auch Sie sich mit Ihrem Unternehmen auf [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":309,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/posts\/2000"}],"collection":[{"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/comments?post=2000"}],"version-history":[{"count":7,"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/posts\/2000\/revisions"}],"predecessor-version":[{"id":2029,"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/posts\/2000\/revisions\/2029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/media\/309"}],"wp:attachment":[{"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/media?parent=2000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/categories?post=2000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smart-ai-work.de\/index.php\/wp-json\/wp\/v2\/tags?post=2000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}